{"id":3046,"date":"2015-06-03T14:58:01","date_gmt":"2015-06-03T14:58:01","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=3046"},"modified":"2018-04-21T19:43:28","modified_gmt":"2018-04-21T19:43:28","slug":"perfect-candies","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/","title":{"rendered":"Perfect Candies"},"content":{"rendered":"<p><a href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3047\" src=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg\" alt=\"perfect-candies\" width=\"810\" height=\"926\" srcset=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg 810w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies-262x300.jpg 262w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies-48x55.jpg 48w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies-638x729.jpg 638w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":3047,"parent":4449,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[5],"tags":[18],"class_list":["post-3046","page","type-page","status-publish","has-post-thumbnail","hentry","category-desserts","tag-candy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perfect Candies - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perfect Candies - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-21T19:43:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"926\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/\",\"name\":\"Perfect Candies - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/perfect-candies.jpg\",\"datePublished\":\"2015-06-03T14:58:01+00:00\",\"dateModified\":\"2018-04-21T19:43:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/perfect-candies.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/perfect-candies.jpg\",\"width\":810,\"height\":926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/perfect-candies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desserts\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Candy\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/candy\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Perfect Candies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perfect Candies - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/","og_locale":"en_US","og_type":"article","og_title":"Perfect Candies - Tim's Mom's Cook Books","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2018-04-21T19:43:28+00:00","og_image":[{"width":810,"height":926,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/","name":"Perfect Candies - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg","datePublished":"2015-06-03T14:58:01+00:00","dateModified":"2018-04-21T19:43:28+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/perfect-candies.jpg","width":810,"height":926},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/perfect-candies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Desserts","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/"},{"@type":"ListItem","position":3,"name":"Candy","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/candy\/"},{"@type":"ListItem","position":4,"name":"Perfect Candies"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=3046"}],"version-history":[{"count":1,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3046\/revisions"}],"predecessor-version":[{"id":3048,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3046\/revisions\/3048"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/3047"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=3046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=3046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=3046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}