{"id":3043,"date":"2015-04-03T14:56:52","date_gmt":"2015-04-03T14:56:52","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=3043"},"modified":"2018-04-21T19:42:00","modified_gmt":"2018-04-21T19:42:00","slug":"pecan-streusel-coffee-cake","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/","title":{"rendered":"Pecan Streusel Coffee Cake"},"content":{"rendered":"<p><a href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3044\" src=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg\" alt=\"pecan-streusel-coffee-cake\" width=\"369\" height=\"1127\" srcset=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg 369w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake-98x300.jpg 98w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake-335x1024.jpg 335w, https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake-18x55.jpg 18w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":3044,"parent":4444,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[4],"tags":[25],"class_list":["post-3043","page","type-page","status-publish","has-post-thumbnail","hentry","category-breads-and-baked-goods","tag-coffee-cakes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pecan Streusel Coffee Cake - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pecan Streusel Coffee Cake - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-21T19:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"369\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/\",\"name\":\"Pecan Streusel Coffee Cake - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/pecan-streusel-coffee-cake.jpg\",\"datePublished\":\"2015-04-03T14:56:52+00:00\",\"dateModified\":\"2018-04-21T19:42:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/pecan-streusel-coffee-cake.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/pecan-streusel-coffee-cake.jpg\",\"width\":369,\"height\":1127},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/pecan-streusel-coffee-cake\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desserts\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cakes\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pecan Streusel Coffee Cake\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pecan Streusel Coffee Cake - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/","og_locale":"en_US","og_type":"article","og_title":"Pecan Streusel Coffee Cake - Tim's Mom's Cook Books","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2018-04-21T19:42:00+00:00","og_image":[{"width":369,"height":1127,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/","name":"Pecan Streusel Coffee Cake - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg","datePublished":"2015-04-03T14:56:52+00:00","dateModified":"2018-04-21T19:42:00+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/06\/pecan-streusel-coffee-cake.jpg","width":369,"height":1127},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/pecan-streusel-coffee-cake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Desserts","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/"},{"@type":"ListItem","position":3,"name":"Cakes","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/"},{"@type":"ListItem","position":4,"name":"Pecan Streusel Coffee Cake"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=3043"}],"version-history":[{"count":1,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3043\/revisions"}],"predecessor-version":[{"id":3045,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/3043\/revisions\/3045"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/3044"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=3043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=3043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=3043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}