{"id":2522,"date":"2015-03-09T19:41:36","date_gmt":"2015-03-09T19:41:36","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=2522"},"modified":"2023-09-29T15:24:18","modified_gmt":"2023-09-29T15:24:18","slug":"creamy-baked-cheesecake","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/","title":{"rendered":"Creamy Baked Cheesecake"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":6706,"parent":4444,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[5],"tags":[16],"class_list":["post-2522","page","type-page","status-publish","has-post-thumbnail","hentry","category-desserts","tag-cakes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creamy Baked Cheesecake - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creamy Baked Cheesecake - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T15:24:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/creamy-baked-cheesecake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"798\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/\",\"name\":\"Creamy Baked Cheesecake - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/creamy-baked-cheesecake.jpg\",\"datePublished\":\"2015-03-09T19:41:36+00:00\",\"dateModified\":\"2023-09-29T15:24:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/creamy-baked-cheesecake.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/creamy-baked-cheesecake.jpg\",\"width\":798,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/creamy-baked-cheesecake\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desserts\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cakes\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Creamy Baked Cheesecake\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creamy Baked Cheesecake - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/","og_locale":"en_US","og_type":"article","og_title":"Creamy Baked Cheesecake - Tim's Mom's Cook Books","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2023-09-29T15:24:18+00:00","og_image":[{"width":798,"height":433,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/creamy-baked-cheesecake.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/","name":"Creamy Baked Cheesecake - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/creamy-baked-cheesecake.jpg","datePublished":"2015-03-09T19:41:36+00:00","dateModified":"2023-09-29T15:24:18+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/creamy-baked-cheesecake.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/creamy-baked-cheesecake.jpg","width":798,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/creamy-baked-cheesecake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Desserts","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/"},{"@type":"ListItem","position":3,"name":"Cakes","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/"},{"@type":"ListItem","position":4,"name":"Creamy Baked Cheesecake"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=2522"}],"version-history":[{"count":2,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2522\/revisions"}],"predecessor-version":[{"id":6707,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2522\/revisions\/6707"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/6706"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=2522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=2522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=2522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}