{"id":2183,"date":"2015-02-23T20:40:29","date_gmt":"2015-02-23T20:40:29","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=2183"},"modified":"2023-09-29T19:27:25","modified_gmt":"2023-09-29T19:27:25","slug":"applesauce-spice-cake-2","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/","title":{"rendered":"Applesauce Spice Cake"},"content":{"rendered":"<p><a href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/02\/applesauce-spice-cake-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2184\" src=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/02\/applesauce-spice-cake-2.jpg\" alt=\"applesauce-spice-cake-2\" width=\"353\" height=\"989\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":6769,"parent":4444,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[5],"tags":[16],"class_list":["post-2183","page","type-page","status-publish","has-post-thumbnail","hentry","category-desserts","tag-cakes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Applesauce Spice Cake - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Applesauce Spice Cake - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T19:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/applesauce-spice-cake-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"353\" \/>\n\t<meta property=\"og:image:height\" content=\"989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/\",\"name\":\"Applesauce Spice Cake - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/applesauce-spice-cake-2.jpg\",\"datePublished\":\"2015-02-23T20:40:29+00:00\",\"dateModified\":\"2023-09-29T19:27:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/applesauce-spice-cake-2.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/applesauce-spice-cake-2.jpg\",\"width\":353,\"height\":989},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/applesauce-spice-cake-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desserts\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cakes\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/desserts-2\\\/cakes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Applesauce Spice Cake\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Applesauce Spice Cake - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/","og_locale":"en_US","og_type":"article","og_title":"Applesauce Spice Cake - Tim's Mom's Cook Books","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2023-09-29T19:27:25+00:00","og_image":[{"width":353,"height":989,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/applesauce-spice-cake-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/","name":"Applesauce Spice Cake - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/applesauce-spice-cake-2.jpg","datePublished":"2015-02-23T20:40:29+00:00","dateModified":"2023-09-29T19:27:25+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/applesauce-spice-cake-2.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/applesauce-spice-cake-2.jpg","width":353,"height":989},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/applesauce-spice-cake-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Desserts","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/"},{"@type":"ListItem","position":3,"name":"Cakes","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/desserts-2\/cakes\/"},{"@type":"ListItem","position":4,"name":"Applesauce Spice Cake"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=2183"}],"version-history":[{"count":1,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2183\/revisions"}],"predecessor-version":[{"id":3675,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/2183\/revisions\/3675"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/6769"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=2183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=2183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=2183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}