{"id":1772,"date":"2015-02-16T01:31:09","date_gmt":"2015-02-16T01:31:09","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=1772"},"modified":"2023-09-30T20:14:26","modified_gmt":"2023-09-30T20:14:26","slug":"sweet-and-sour-pork-with-noodles","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/","title":{"rendered":"Sweet and Sour Pork with Noodles"},"content":{"rendered":"<p><a href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/02\/sweet-and-sour-pork-with-noodles.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-1773\" src=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2015\/02\/sweet-and-sour-pork-with-noodles.jpg\" alt=\"sweet-and-sour-pork-with-noodles\" width=\"380\" height=\"905\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":6951,"parent":4501,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[6],"tags":[22,51],"class_list":["post-1772","page","type-page","status-publish","has-post-thumbnail","hentry","category-entrees","tag-chinese","tag-pork"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sweet and Sour Pork with Noodles - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sweet and Sour Pork with Noodles - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-30T20:14:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/sweet-and-sour-pork-with-noodles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/\",\"name\":\"Sweet and Sour Pork with Noodles - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sweet-and-sour-pork-with-noodles.jpg\",\"datePublished\":\"2015-02-16T01:31:09+00:00\",\"dateModified\":\"2023-09-30T20:14:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sweet-and-sour-pork-with-noodles.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/sweet-and-sour-pork-with-noodles.jpg\",\"width\":380,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/sweet-and-sour-pork-with-noodles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entr\u00e9es\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pork\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/entrees-2\\\/pork\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sweet and Sour Pork with Noodles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sweet and Sour Pork with Noodles - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/","og_locale":"en_US","og_type":"article","og_title":"Sweet and Sour Pork with Noodles - Tim's Mom's Cook Books","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2023-09-30T20:14:26+00:00","og_image":[{"width":380,"height":905,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/sweet-and-sour-pork-with-noodles.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/","name":"Sweet and Sour Pork with Noodles - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/sweet-and-sour-pork-with-noodles.jpg","datePublished":"2015-02-16T01:31:09+00:00","dateModified":"2023-09-30T20:14:26+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/sweet-and-sour-pork-with-noodles.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2023\/09\/sweet-and-sour-pork-with-noodles.jpg","width":380,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/sweet-and-sour-pork-with-noodles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Entr\u00e9es","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/"},{"@type":"ListItem","position":3,"name":"Pork","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/entrees-2\/pork\/"},{"@type":"ListItem","position":4,"name":"Sweet and Sour Pork with Noodles"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=1772"}],"version-history":[{"count":1,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1772\/revisions"}],"predecessor-version":[{"id":3798,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1772\/revisions\/3798"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/6951"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=1772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=1772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=1772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}