{"id":1255,"date":"2015-01-29T14:00:21","date_gmt":"2015-01-29T14:00:21","guid":{"rendered":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?p=1255"},"modified":"2020-04-05T19:14:16","modified_gmt":"2020-04-05T19:14:16","slug":"mushrooms-monterey","status":"publish","type":"page","link":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/","title":{"rendered":"Mushrooms Monterey"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row section_type=&#8221;fullwidth&#8221; bg_type=&#8221;color&#8221; padding_top_multiplier=&#8221;&#8221; padding_bottom_multiplier=&#8221;&#8221; bg_color=&#8221;#c5a1e2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column vertical_content_position=&#8221;middle&#8221; width=&#8221;2\/3&#8243; text_align=&#8221;center&#8221; css=&#8221;.vc_custom_1585415440035{margin-top: 50px !important;}&#8221;][movedo_single_image image_type=&#8221;image-popup&#8221; image=&#8221;5556&#8243; shadow=&#8221;large&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1585414868161{margin-left: 75px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1585681834070{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Appetizers<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Appetizers&#8221; tab_id=&#8221;1585407956556-857d5e1a-43bd659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ2JTIyJTVE[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css=&#8221;.vc_custom_1585681842941{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Soups-Salads-Sides<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Salads&#8221; tab_id=&#8221;1585408508389-4582bc13-6f26659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0ODclMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Sides&#8221; tab_id=&#8221;1585408508406-9d02b377-7734659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0OTElMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Soups&#8221; tab_id=&#8221;1585408620837-5956bb11-9402659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0ODUlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css=&#8221;.vc_custom_1585681863717{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Entr\u00e9es<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Beef&#8221; tab_id=&#8221;1585410268316-6820ba1e-ad07659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0OTclMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Pork&#8221; tab_id=&#8221;1585410268327-39e9af76-7bf6659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ1MDElMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Poultry&#8221; tab_id=&#8221;1585410520180-b4367202-ec0c659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0OTklMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Seafood&#8221; tab_id=&#8221;1585410555211-7a706a41-fdbd659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ1MDMlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Vegetarian&#8221; tab_id=&#8221;1585410651209-c67e8ce7-e2e4659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ1MDUlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css=&#8221;.vc_custom_1585681955037{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Bakery<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Breads and Rolls&#8221; tab_id=&#8221;1585412718263-501b7fb9-fa25659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ1MTElMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Quick Breads, Muffins, and Crackers&#8221; tab_id=&#8221;1585412718277-cccc039e-6692659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NTEzJTIyJTVE[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Sweet Breads and Coffee Cakes&#8221; tab_id=&#8221;1585412827560-7a376bb7-dad7659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ1MTUlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css=&#8221;.vc_custom_1585681970854{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Desserts<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Bars and Brownies&#8221; tab_id=&#8221;1585413916906-83d3b988-82b6659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NDIlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Cakes&#8221; tab_id=&#8221;1585413916923-a49828a4-2eea659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NDQlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Candy&#8221; tab_id=&#8221;1585414034605-3170b96c-7d26659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NDklMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Cookies&#8221; tab_id=&#8221;1585414069703-4e0f66c2-83d6659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NDclMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Custards and Puddings&#8221; tab_id=&#8221;1585414127078-875602c5-4b02659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NTElMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Fruit Desserts&#8221; tab_id=&#8221;1585414167926-8cea965f-9951659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NTQlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Ice Cream and Frozen Desserts&#8221; tab_id=&#8221;1585414278725-190ff18e-7428659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NTYlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][vc_tta_section title=&#8221;Pies and Cobblers&#8221; tab_id=&#8221;1585414341501-a5a8876b-6a1e659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjQ0NTglMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][vc_column_text css=&#8221;.vc_custom_1585681988293{padding-top: 25px !important;padding-bottom: 25px !important;}&#8221;]<\/p>\n<h3>Miscellaneous<\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;0&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;Miscellaneous&#8221; tab_id=&#8221;1585414418586-168edb3a-db9d659c-41b39746-2d6d&#8221;][vc_raw_html]JTVCcGFnZWxpc3QlMjBjaGlsZF9vZiUzRCUyMjM5MDAlMjIlNUQ=[\/vc_raw_html][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row section_type=&#8221;fullwidth&#8221; bg_type=&#8221;color&#8221; padding_top_multiplier=&#8221;&#8221; padding_bottom_multiplier=&#8221;&#8221; bg_color=&#8221;#c5a1e2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column vertical_content_position=&#8221;middle&#8221; width=&#8221;2\/3&#8243; text_align=&#8221;center&#8221; css=&#8221;.vc_custom_1585415440035{margin-top: 50px !important;}&#8221;][movedo_single_image image_type=&#8221;image-popup&#8221; image=&#8221;5556&#8243; shadow=&#8221;large&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1585414868161{margin-left: 75px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1585681834070{padding-top: [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5556,"parent":4491,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[8],"tags":[59],"class_list":["post-1255","page","type-page","status-publish","has-post-thumbnail","hentry","category-soups-salads-and-sides","tag-sauces"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mushrooms Monterey - Tim&#039;s Mom&#039;s Cook Books<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mushrooms Monterey - Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"og:description\" content=\"[vc_row section_type=&#8221;fullwidth&#8221; bg_type=&#8221;color&#8221; padding_top_multiplier=&#8221;&#8221; padding_bottom_multiplier=&#8221;&#8221; bg_color=&#8221;#c5a1e2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column vertical_content_position=&#8221;middle&#8221; width=&#8221;2\/3&#8243; text_align=&#8221;center&#8221; css=&#8221;.vc_custom_1585415440035{margin-top: 50px !important;}&#8221;][movedo_single_image image_type=&#8221;image-popup&#8221; image=&#8221;5556&#8243; shadow=&#8221;large&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1585414868161{margin-left: 75px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1585681834070{padding-top: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/\" \/>\n<meta property=\"og:site_name\" content=\"Tim&#039;s Mom&#039;s Cook Books\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-05T19:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2020\/04\/mushrooms-momterey.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"359\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/\",\"name\":\"Mushrooms Monterey - Tim's Mom's Cook Books\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/mushrooms-momterey.jpg\",\"datePublished\":\"2015-01-29T14:00:21+00:00\",\"dateModified\":\"2020-04-05T19:14:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/mushrooms-momterey.jpg\",\"contentUrl\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/mushrooms-momterey.jpg\",\"width\":359,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/mushrooms-monterey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soups, Salads, &#038; Sides\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sides\",\"item\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/soups-salads-sides\\\/sides\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mushrooms Monterey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/#website\",\"url\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/\",\"name\":\"Tim's Mom's Cook Books\",\"description\":\"Food Fun from the '60s and '70s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tjrecipes.com\\\/tims-moms-cookbooks\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mushrooms Monterey - Tim's Mom's Cook Books","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/","og_locale":"en_US","og_type":"article","og_title":"Mushrooms Monterey - Tim's Mom's Cook Books","og_description":"[vc_row section_type=&#8221;fullwidth&#8221; bg_type=&#8221;color&#8221; padding_top_multiplier=&#8221;&#8221; padding_bottom_multiplier=&#8221;&#8221; bg_color=&#8221;#c5a1e2&#8243;][vc_column][\/vc_column][\/vc_row][vc_row][vc_column vertical_content_position=&#8221;middle&#8221; width=&#8221;2\/3&#8243; text_align=&#8221;center&#8221; css=&#8221;.vc_custom_1585415440035{margin-top: 50px !important;}&#8221;][movedo_single_image image_type=&#8221;image-popup&#8221; image=&#8221;5556&#8243; shadow=&#8221;large&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1585414868161{margin-left: 75px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1585681834070{padding-top: [&hellip;]","og_url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/","og_site_name":"Tim's Mom's Cook Books","article_modified_time":"2020-04-05T19:14:16+00:00","og_image":[{"width":359,"height":485,"url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2020\/04\/mushrooms-momterey.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/","name":"Mushrooms Monterey - Tim's Mom's Cook Books","isPartOf":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/#primaryimage"},"image":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/#primaryimage"},"thumbnailUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2020\/04\/mushrooms-momterey.jpg","datePublished":"2015-01-29T14:00:21+00:00","dateModified":"2020-04-05T19:14:16+00:00","breadcrumb":{"@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/#primaryimage","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2020\/04\/mushrooms-momterey.jpg","contentUrl":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-content\/uploads\/2020\/04\/mushrooms-momterey.jpg","width":359,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/mushrooms-monterey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/"},{"@type":"ListItem","position":2,"name":"Soups, Salads, &#038; Sides","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/"},{"@type":"ListItem","position":3,"name":"Sides","item":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/soups-salads-sides\/sides\/"},{"@type":"ListItem","position":4,"name":"Mushrooms Monterey"}]},{"@type":"WebSite","@id":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/#website","url":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/","name":"Tim's Mom's Cook Books","description":"Food Fun from the '60s and '70s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"}]}},"_links":{"self":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":2,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1255\/revisions"}],"predecessor-version":[{"id":5557,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/1255\/revisions\/5557"}],"up":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/pages\/4491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media\/5556"}],"wp:attachment":[{"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjrecipes.com\/tims-moms-cookbooks\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}